{"id":1494,"date":"2020-04-18T11:50:47","date_gmt":"2020-04-18T18:50:47","guid":{"rendered":"https:\/\/wirtzlawstg.wpengine.com\/?p=1494"},"modified":"2023-04-25T18:34:01","modified_gmt":"2023-04-25T22:34:01","slug":"que-significa-intencionado-en-la-ley-del-limon-de-california","status":"publish","type":"post","link":"https:\/\/www.wirtzlaw.com\/es\/what-does-willful-mean-under-the-california-lemon-law\/","title":{"rendered":"\u00bfQu\u00e9 significa \"intencionado\" bajo la Ley del Lim\u00f3n de California?"},"content":{"rendered":"<p>Seg\u00fan la <a href=\"https:\/\/leginfo.legislature.ca.gov\/faces\/codes_displayText.xhtml?lawCode=CIV&amp;division=3.&amp;title=1.7.&amp;part=4.&amp;chapter=1.&amp;article=3.\" target=\"_blank\" rel=\"noreferrer noopener\">Ley de garant\u00eda de los consumidores Song-Beverly<\/a>Seg\u00fan la ley del lim\u00f3n de California, un comprador puede recuperar <a href=\"https:\/\/www.wirtzlaw.com\/es\/areas-de-practica\/abogados-de-la-ley-del-limon\/abogado-de-la-ley-del-limon-de-san-diego\/sancion-civil-de-la-ley-del-limon\/\">sanciones civiles<\/a> si el fabricante ha violado intencionadamente la Ley<\/p>\n\n\n\n<p>En este contexto, \"doloso\" significa que el fabricante \"conoc\u00eda sus obligaciones legales y se neg\u00f3 intencionadamente a cumplirlas\". Esto significa que el fabricante sab\u00eda lo que hac\u00eda y ten\u00eda intenci\u00f3n de hacerlo, que sus acciones no fueron accidentales. No requiere que el fabricante haya actuado de mala fe o maliciosamente.<\/p>\n\n\n\n<p>Una infracci\u00f3n no es intencionada si el fabricante cre\u00eda razonablemente y de buena fe que el veh\u00edculo no cumpl\u00eda los requisitos para ser recomprado o sustituido.<\/p>\n\n\n\n<p>Los tribunales han interpretado lo que significa \"intencionado\" en la pr\u00e1ctica:<\/p>\n\n\n\n<p>Si un fabricante se niega a recomprar o sustituir un veh\u00edculo que cumple los requisitos sin realizar ninguna investigaci\u00f3n sobre su cualificaci\u00f3n, podr\u00eda tratarse de una infracci\u00f3n dolosa, ya que \"una decisi\u00f3n tomada sin utilizar la informaci\u00f3n razonablemente disponible relacionada con esa decisi\u00f3n no es una decisi\u00f3n razonable y de buena fe\". (<em>Lukather v. General Motors LLC<\/em> (2010) 181 Cal.App.4th 1041, 1051).<\/p>\n\n\n\n<p>Si un fabricante \"adopta pol\u00edticas internas que erigen obst\u00e1culos ocultos a la capacidad de un consumidor incauto\" para obtener una recompra o sustituci\u00f3n podr\u00eda ser doloso. (<em>Oregel contra American Isuzu Motors, Inc. <\/em>(2001) 90 Cal.App.4th 1094, 1104-1105).<\/p>\n\n\n\n<p><em>Para m\u00e1s informaci\u00f3n llame a los experimentados abogados litigantes de <a href=\"tel:1-858-259-5009\">(858) 259-5009<\/a> para una evaluaci\u00f3n gratuita de su caso.<\/em><\/p>\n\n\n\n<p><em><strong><u>Descargo de responsabilidad<\/u>.<\/strong> La informaci\u00f3n proporcionada en este anuncio es s\u00f3lo para fines informativos y educativos sobre aspectos de la Ley del Lim\u00f3n de California.  Est\u00e1 dirigida \u00fanicamente a los consumidores de California.  Esta presentaci\u00f3n se considera un anuncio del abogado Richard M. Wirtz y Wirtz Law APC. Usted no debe confiar en ninguna de la informaci\u00f3n proporcionada en este anuncio y ning\u00fan consejo legal es dado por el anuncio. No se establece ninguna relaci\u00f3n abogado-cliente por ver este anuncio. Se requiere un acuerdo de compromiso por escrito firmado entre usted y Wirtz Law APC para crear una relaci\u00f3n abogado-cliente. Usted debe consultar inmediatamente a un abogado con experiencia en la Ley del Lim\u00f3n de California. El abogado Richard M. Wirtz es responsable del contenido de este anuncio.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan la Ley Song-Beverly de Garant\u00edas del Consumidor, la ley del lim\u00f3n de California, un comprador puede recuperar las sanciones civiles si el fabricante infringi\u00f3 intencionadamente la Ley En este contexto, \"intencionadamente\" significa que el fabricante \"conoc\u00eda sus obligaciones legales y se neg\u00f3 intencionadamente a cumplirlas\". Esto significa que el fabricante sab\u00eda lo que hac\u00eda y ten\u00eda intenci\u00f3n de hacerlo...<\/p>","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1494","post","type-post","status-publish","format-standard","hentry","category-california-lemon-law"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/posts\/1494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/comments?post=1494"}],"version-history":[{"count":2,"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/posts\/1494\/revisions"}],"predecessor-version":[{"id":5240,"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/posts\/1494\/revisions\/5240"}],"wp:attachment":[{"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/media?parent=1494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/categories?post=1494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wirtzlaw.com\/es\/wp-json\/wp\/v2\/tags?post=1494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}